{"id":8344,"date":"2026-01-28T10:19:24","date_gmt":"2026-01-28T10:19:24","guid":{"rendered":"https:\/\/indpuls.tech\/es\/blog\/\/"},"modified":"2026-02-16T11:24:59","modified_gmt":"2026-02-16T11:24:59","slug":"la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas","status":"publish","type":"post","link":"https:\/\/indpuls.tech\/es\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/","title":{"rendered":"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas"},"content":{"rendered":"\n<div class=\"omt-prose-container wp-block-omt-prose-container\">\n\n\t<div class=\"acf-innerblocks-container\">\n\n<p>En el marco de la jornada del <a href=\"https:\/\/indpuls.tech\/es\/blog\/ai-adoption-program-accelerating-industrial-transformation-with-high-impact-solutions\/\">AI Adoption Program<\/a> 2025-2026 (proyecto financiado por el<br>Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia &#8211; Financiado por la Uni\u00f3n Europea &#8211; NextGenerationEU), se celebr\u00f3 la masterclass <strong>IA para nuevos productos y modelos de negocio<\/strong>, a cargo de <strong>Albert Esplugas<\/strong>, ejecutivo tecnol\u00f3gico global y l\u00edder en estrategia de IA con m\u00e1s de 20 a\u00f1os de experiencia impulsando iniciativas de Inteligencia Artificial, IA generativa e innovaci\u00f3n en Amazon Web Services, Microsoft y Apple. Una sesi\u00f3n, en <strong>La Casa de la Llum de Simon<\/strong>, que reuni\u00f3 a los socios industriales de INDPULS con las 10 startups y pymes tecnol\u00f3gicas finalistas del programa.<\/p>\n\n\n\n<div\n\tclass=\"omt-qoute wp-block-omt-qoute\"\t>\n\t\t\t<div class=\"omt-qoute__wrapper\">\n\t\t\t<div class=\"omt-qoute__deatils-block\">\n\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\tLa conferencia puso el foco en una idea clave: la inteligencia artificial no es solo una herramienta de mejora de la eficiencia, sino tambi\u00e9n una tecnolog\u00eda capaz de redefinir completamente c\u00f3mo se dise\u00f1an productos, procesos y modelos de negocio.\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-font-size-xl-font-size\"><strong>De la automatizaci\u00f3n al redise\u00f1o<\/strong><\/p>\n\n\n\n<div\n\tclass=\"omt-image-content wp-block-omt-image-content\"\t>\n\n\t<div class=\"omt-image-content__wrapper\">\n\t\t<div class=\"omt-image-content__img-block\">\n\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/albert-esplugas-indpuls-AI.jpg\" class=\"omt-image-content__img\" alt=\"\" srcset=\"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/albert-esplugas-indpuls-AI.jpg 600w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/albert-esplugas-indpuls-AI-300x300.jpg 300w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/albert-esplugas-indpuls-AI-150x150.jpg 150w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/albert-esplugas-indpuls-AI-390x390.jpg 390w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n\t\t<\/div>\n\t\t<div class=\"omt-image-content__deatils-block\">\n\t\t\t<p data-start=\"946\" data-end=\"1314\">Durante la sesi\u00f3n, Esplugas describi\u00f3 la IA como \u201celectricidad cognitiva\u201d. Un paralelismo especialmente significativo teniendo en cuenta el espacio donde se celebr\u00f3 la jornada, La Casa de la Llum. La electricidad no transform\u00f3 la industria cuando sustituy\u00f3 al vapor, sino cuando permiti\u00f3 redise\u00f1ar las f\u00e1bricas. Con la IA ocurre exactamente lo mismo, seg\u00fan Esplugas.<\/p>\n<p data-start=\"1316\" data-end=\"1590\">La mayor\u00eda de las organizaciones utilizan la IA para automatizar tareas concretas. Pero el verdadero salto de valor llega cuando se replantean procesos completos, estructuras organizativas y propuestas de valor. <strong>El retorno no proviene de la herramienta, sino del redise\u00f1o.<\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-font-size-xl-font-size\"><strong>La evoluci\u00f3n natural de la inteligencia artificial<\/strong><\/p>\n\n\n\n<p>Esplugas estructura la evoluci\u00f3n de la <strong>IA en varias etapas claras<\/strong>. Primero, las demos cient\u00edficas y la curiosidad tecnol\u00f3gica. Despu\u00e9s, los primeros usos \u00fatiles basados en anal\u00edtica predictiva y cognitiva. M\u00e1s adelante, las killer apps, como los asistentes inteligentes. A continuaci\u00f3n, la construcci\u00f3n de infraestructura: datos, Machine Learning Operations, est\u00e1ndares, gobernanza y regulaci\u00f3n.<\/p>\n\n\n\n<p><strong>El punto clave llega con el salto real: el redise\u00f1o profundo de procesos y organizaciones<\/strong>. Finalmente, una IA invisible, integrada de forma natural en todos los sistemas, productos y decisiones. No como una capa a\u00f1adida, sino como una capacidad estructural.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-font-size-xl-font-size\"><strong>Nuevos productos, nuevos modelos de negocio<\/strong><\/p>\n\n\n\n<p>Uno de los mensajes centrales de la sesi\u00f3n fue la necesidad de ir m\u00e1s all\u00e1 de la eficiencia interna. La IA habilita nuevos productos, servicios y modelos de negocio que antes no eran posibles. La pregunta estrat\u00e9gica se centra en saber qu\u00e9 proceso hay que redise\u00f1ar y qu\u00e9 nuevo valor podemos ofrecer al mercado.<\/p>\n\n\n\n<p>En este contexto, la IA se convierte en un vector de transformaci\u00f3n transversal que impacta directamente en m\u00faltiples dimensiones del negocio:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lo que vendemos<\/li>\n\n\n\n<li>C\u00f3mo lo vendemos<\/li>\n\n\n\n<li>A qui\u00e9n se lo vendemos<\/li>\n\n\n\n<li>C\u00f3mo trabajamos<\/li>\n\n\n\n<li>C\u00f3mo operamos<\/li>\n\n\n\n<li>C\u00f3mo tomamos decisiones<\/li>\n\n\n\n<li>Qu\u00e9 cobramos<\/li>\n\n\n\n<li>C\u00f3mo competimos<\/li>\n\n\n\n<li>C\u00f3mo innovamos<\/li>\n<\/ul>\n\n\n\n<p>Durante la sesi\u00f3n, esta <strong>visi\u00f3n se reforz\u00f3 con numerosos ejemplos concretos de c\u00f3mo la IA ya est\u00e1 transformando estas \u00e1reas en distintos sectores industriales<\/strong>, demostrando su potencial real para generar ventaja competitiva y abrir nuevas oportunidades de crecimiento.<\/p>\n\n\n\n<div\n\tclass=\"omt-qoute wp-block-omt-qoute\"\t>\n\t\t\t<div class=\"omt-qoute__wrapper\">\n\t\t\t<div class=\"omt-qoute__deatils-block\">\n\t\t\t\t<p>\n\t\t\t\t\t\t\t\t\t\tEsta visi\u00f3n encaja con el objetivo del AI Adoption Program: convertir casos de uso industriales en pilotos de IA reales, operativos y escalables, conectando necesidades concretas con soluciones tecnol\u00f3gicas de alto impacto.\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-font-size-xl-font-size\"><strong>Industria y tecnolog\u00eda, alineadas en retos reales<\/strong><\/p>\n\n\n\n<div\n\tclass=\"omt-image-content wp-block-omt-image-content\"\t>\n\n\t<div class=\"omt-image-content__wrapper\">\n\t\t<div class=\"omt-image-content__img-block\">\n\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/Rediseno-IA-Albert-Esplugas-Indpuls.jpg\" class=\"omt-image-content__img\" alt=\"\" srcset=\"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/Rediseno-IA-Albert-Esplugas-Indpuls.jpg 900w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/Rediseno-IA-Albert-Esplugas-Indpuls-300x300.jpg 300w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/Rediseno-IA-Albert-Esplugas-Indpuls-150x150.jpg 150w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/Rediseno-IA-Albert-Esplugas-Indpuls-768x768.jpg 768w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/Rediseno-IA-Albert-Esplugas-Indpuls-390x390.jpg 390w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\n\t\t<\/div>\n\t\t<div class=\"omt-image-content__deatils-block\">\n\t\t\t<p data-start=\"3595\" data-end=\"3879\">La jornada reforz\u00f3 uno de los pilares de INDPULS: la colaboraci\u00f3n efectiva entre industria y tecnolog\u00eda. <strong>Cuando startups, pymes tecnol\u00f3gicas y grandes grupos industriales trabajan conjuntamente sobre retos reales, la innovaci\u00f3n deja de ser te\u00f3rica y se convierte en impacto medible.<\/strong><\/p>\n<p data-start=\"3881\" data-end=\"4071\" data-is-last-node=\"\" data-is-only-node=\"\"><strong>La IA no es el destino final. Es el catalizador. La verdadera ventaja competitiva est\u00e1 en saber d\u00f3nde y c\u00f3mo redise\u00f1ar.<\/strong> Y ese es, precisamente, el camino que estamos activando desde INDPULS.<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Con el apoyo de:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"112\" src=\"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/logos-articles-1024x112.png\" alt=\"\" class=\"wp-image-8555\" srcset=\"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/logos-articles-1024x112.png 1024w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/logos-articles-300x33.png 300w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/logos-articles-768x84.png 768w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/logos-articles-480x53.png 480w, https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/logos-articles.png 1139w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<\/div>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la jornada del AI Adoption Program 2025-2026, se celebr\u00f3 la masterclass IA para nuevos productos y modelos de negocio<\/p>\n","protected":false},"author":8,"featured_media":8342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[137,117,121],"tags":[],"class_list":["post-8344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ai-adoption-program","category-startups-es","category-tech-industry-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas - INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas<\/title>\n<meta name=\"description\" content=\"En el marco de la jornada del AI Adoption Program 2025-2026, se celebr\u00f3 la masterclass IA para nuevos productos y modelos de negocio...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas - INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas\" \/>\n<meta property=\"og:description\" content=\"En el marco de la jornada del AI Adoption Program 2025-2026, se celebr\u00f3 la masterclass IA para nuevos productos y modelos de negocio...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/\" \/>\n<meta property=\"og:site_name\" content=\"INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-28T10:19:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T11:24:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina Roda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@INDPULS_Tech\" \/>\n<meta name=\"twitter:site\" content=\"@INDPULS_Tech\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristina Roda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/\"},\"author\":{\"name\":\"Cristina Roda\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#\\\/schema\\\/person\\\/bec5bf4fda16aaaa1e4e8ab0729228c9\"},\"headline\":\"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas\",\"datePublished\":\"2026-01-28T10:19:24+00:00\",\"dateModified\":\"2026-02-16T11:24:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/\"},\"wordCount\":418,\"publisher\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/indpuls.tech\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg\",\"articleSection\":[\"AI Adoption Program\",\"Startups\",\"Tecnolog\u00eda e industria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/\",\"url\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/\",\"name\":\"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas - INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/indpuls.tech\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg\",\"datePublished\":\"2026-01-28T10:19:24+00:00\",\"dateModified\":\"2026-02-16T11:24:59+00:00\",\"description\":\"En el marco de la jornada del AI Adoption Program 2025-2026, se celebr\u00f3 la masterclass IA para nuevos productos y modelos de negocio...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/indpuls.tech\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg\",\"contentUrl\":\"https:\\\/\\\/indpuls.tech\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/blog\\\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/indpuls.tech\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/\",\"name\":\"INDPULS\",\"description\":\"En Indpuls apostamos por el compromiso con la innovaci\u00f3n y el crecimiento empresarial sostenible en el nuevo ecosistema digital.\",\"publisher\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#organization\",\"name\":\"INDPULS\",\"url\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/indpuls.tech\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/indpuls.tech\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/header-logo.svg\",\"width\":204,\"height\":27,\"caption\":\"INDPULS\"},\"image\":{\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/INDPULS_Tech\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/indpuls-tech\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/indpuls.tech\\\/en\\\/#\\\/schema\\\/person\\\/bec5bf4fda16aaaa1e4e8ab0729228c9\",\"name\":\"Cristina Roda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/276efd9cf152d89c663dd6217f0fe9650c02ebd28eac742a0a7ae3e956679e48?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/276efd9cf152d89c663dd6217f0fe9650c02ebd28eac742a0a7ae3e956679e48?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/276efd9cf152d89c663dd6217f0fe9650c02ebd28eac742a0a7ae3e956679e48?s=96&d=mm&r=g\",\"caption\":\"Cristina Roda\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas - INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas","description":"En el marco de la jornada del AI Adoption Program 2025-2026, se celebr\u00f3 la masterclass IA para nuevos productos y modelos de negocio...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/","og_locale":"es_ES","og_type":"article","og_title":"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas - INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas","og_description":"En el marco de la jornada del AI Adoption Program 2025-2026, se celebr\u00f3 la masterclass IA para nuevos productos y modelos de negocio...","og_url":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/","og_site_name":"INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas","article_published_time":"2026-01-28T10:19:24+00:00","article_modified_time":"2026-02-16T11:24:59+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg","type":"image\/jpeg"}],"author":"Cristina Roda","twitter_card":"summary_large_image","twitter_creator":"@INDPULS_Tech","twitter_site":"@INDPULS_Tech","twitter_misc":{"Escrito por":"Cristina Roda","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/#article","isPartOf":{"@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/"},"author":{"name":"Cristina Roda","@id":"https:\/\/indpuls.tech\/en\/#\/schema\/person\/bec5bf4fda16aaaa1e4e8ab0729228c9"},"headline":"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas","datePublished":"2026-01-28T10:19:24+00:00","dateModified":"2026-02-16T11:24:59+00:00","mainEntityOfPage":{"@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/"},"wordCount":418,"publisher":{"@id":"https:\/\/indpuls.tech\/en\/#organization"},"image":{"@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/#primaryimage"},"thumbnailUrl":"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg","articleSection":["AI Adoption Program","Startups","Tecnolog\u00eda e industria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/","url":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/","name":"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas - INDPULS | Innovaci\u00f3n colaborativa entre startups y empresas","isPartOf":{"@id":"https:\/\/indpuls.tech\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/#primaryimage"},"image":{"@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/#primaryimage"},"thumbnailUrl":"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg","datePublished":"2026-01-28T10:19:24+00:00","dateModified":"2026-02-16T11:24:59+00:00","description":"En el marco de la jornada del AI Adoption Program 2025-2026, se celebr\u00f3 la masterclass IA para nuevos productos y modelos de negocio...","breadcrumb":{"@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/#primaryimage","url":"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg","contentUrl":"https:\/\/indpuls.tech\/wp-content\/uploads\/2026\/01\/IA-GENERATIVA-ALBERT-ESPLUGAS-INDPULS.jpg","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/indpuls.tech\/en\/blog\/la-ia-para-transformar-productos-y-modelos-de-negocio-a-cargo-de-albert-esplugas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/indpuls.tech\/es\/"},{"@type":"ListItem","position":2,"name":"La IA para transformar productos y modelos de negocio, a cargo de Albert Esplugas"}]},{"@type":"WebSite","@id":"https:\/\/indpuls.tech\/en\/#website","url":"https:\/\/indpuls.tech\/en\/","name":"INDPULS","description":"En Indpuls apostamos por el compromiso con la innovaci\u00f3n y el crecimiento empresarial sostenible en el nuevo ecosistema digital.","publisher":{"@id":"https:\/\/indpuls.tech\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indpuls.tech\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/indpuls.tech\/en\/#organization","name":"INDPULS","url":"https:\/\/indpuls.tech\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/indpuls.tech\/en\/#\/schema\/logo\/image\/","url":"https:\/\/indpuls.tech\/wp-content\/uploads\/2024\/08\/header-logo.svg","contentUrl":"https:\/\/indpuls.tech\/wp-content\/uploads\/2024\/08\/header-logo.svg","width":204,"height":27,"caption":"INDPULS"},"image":{"@id":"https:\/\/indpuls.tech\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/INDPULS_Tech","https:\/\/www.linkedin.com\/company\/indpuls-tech\/"]},{"@type":"Person","@id":"https:\/\/indpuls.tech\/en\/#\/schema\/person\/bec5bf4fda16aaaa1e4e8ab0729228c9","name":"Cristina Roda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/276efd9cf152d89c663dd6217f0fe9650c02ebd28eac742a0a7ae3e956679e48?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/276efd9cf152d89c663dd6217f0fe9650c02ebd28eac742a0a7ae3e956679e48?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/276efd9cf152d89c663dd6217f0fe9650c02ebd28eac742a0a7ae3e956679e48?s=96&d=mm&r=g","caption":"Cristina Roda"}}]}},"_links":{"self":[{"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/posts\/8344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/comments?post=8344"}],"version-history":[{"count":7,"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/posts\/8344\/revisions"}],"predecessor-version":[{"id":8592,"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/posts\/8344\/revisions\/8592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/media\/8342"}],"wp:attachment":[{"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/media?parent=8344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/categories?post=8344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indpuls.tech\/es\/wp-json\/wp\/v2\/tags?post=8344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}